﻿
{"id":38811,"date":"2018-04-30T17:17:18","date_gmt":"2018-04-30T15:17:18","guid":{"rendered":"https:\/\/www.betten.de\/magazin\/?p=38811"},"modified":"2025-12-01T09:19:48","modified_gmt":"2025-12-01T08:19:48","slug":"schlafen-auf-dem-boden-gesund-ungesund","status":"publish","type":"post","link":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html","title":{"rendered":"Schlafen auf dem Boden &#8211; Gesund, ungesund?"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund.jpg\" alt=\"Ist es gesund oder ungesund auf dem Boden zu schlafen?\" title=\"Auf dem Boden schlafen - gesund oder ungesund (copyright by: contrastwerkstatt | Fotolia.com)\" width=\"424\" height=\"283\" class=\"alignright size-full wp-image-38812\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund.jpg 424w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund-150x100.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund-300x200.jpg 300w\" sizes=\"auto, (max-width: 424px) 100vw, 424px\" \/>In unseren Breiten geben wir bereits seit geraumer Zeit Betten oder bettartigen Konstruktionen mit einer deutlich \u00fcber dem Boden befindlichen Liegefl\u00e4che den Vorzug, wenn es um die Wahl der Schlafst\u00e4tte geht. Nur wenige Menschen w\u00e4hlen in unserer westlichen Welt den Boden als Ruheort f\u00fcr die Nacht aus. Warum dieses so ist, wollen wir in diesem Artikel unseres Schlafmagazins genauer untersuchen. Wir befassen uns in diesem Zusammenhang unter anderem mit Fragen wie \u201eWie gesund ist es, auf dem Boden zu schlafen?\u201c oder \u201eWarum schlafen Japaner auf dem Boden?\u201c.<\/p>\n<div id=\"inhaltsverzeichnis-fullw\" style=\"margin-top:50px;\">\n<div class=\"summary\">Inhaltsverzeichnis:<\/div>\n<ol>\n<li><a href=\"#boden-schlafen-asien\">Auf dem Boden schlafen in Asien<\/a><\/li>\n<li><a href=\"#paleo-bodenschlaf\">Paleo und Bodenschlaf<\/a><\/li>\n<ul>\n<li><a href=\"#was-ist-paleo\">Exkurs: Was ist Paleo?<\/a><\/li>\n<\/ul>\n<li><a href=\"#minimalismus-bodenschlaf\">Minimalismus und Bodenschlaf<\/a><\/li>\n<ul>\n<li><a href=\"#was-ist-minimalismus\">Exkurs: Was ist Minimalismus?<\/a><\/li>\n<\/ul>\n<li><a href=\"#schlafen-boden-gesund-ungesund\">Schlafen auf dem Boden \u2013 Gesund, ungesund ?<\/a><\/li>\n<ul>\n<li><a href=\"#schlafen-boden-gesund\">These: \u201eSchlafen auf dem Boden ist gesund\u201c \u2013 Pro-Argumente<\/a><\/li>\n<li><a href=\"#bequem-erholsam-liegen\">Exkurs: Bequem und erholsames Liegen<\/a><\/li>\n<li><a href=\"#schlafen-boden-ungesund\">These: \u201eSchlafen auf dem Boden ist ungesund\u201c \u2013 Contra-Argumente<\/a><\/li>\n<\/ul>\n<li><a href=\"#auf-dem-boden-schlafen-studien\">Studien: Auf dem Boden schlafen<\/a><\/li>\n<li><a href=\"#tipps-auf-boden-schlafen\">Tipps: Auf dem Boden schlafen<\/a><\/li>\n<li><a href=\"#schlafen-auf-boden-fazit\">Fazit zum Schlafen auf dem Boden<\/a><\/li>\n<\/ol>\n<\/div>\n<p><!-- INHALTSVERZEICHNIS-ENDE --><\/p>\n<hr>\n<p>Bevor wir uns der Fragestellung \u201eIst es gesund oder ungesund, auf dem Boden zu schlafen?\u201c besch\u00e4ftigen wir uns zun\u00e4chst mit ausgew\u00e4hlten Kulturen sowie Lebensstilen, wo der Bodenschlaf breit akzeptiert und praktiziert wird:<\/p>\n<hr>\n<p><a name=\"boden-schlafen-asien\"><\/a><\/p>\n<h2>Auf dem Boden schlafen in Asien<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/boden-bett-mit-tatami-und-futon-300x164.jpg\" alt=\"Westliche Variante des japanischen Futon Bettes mit Tatami und zus\u00e4tzlichem Holzbettgestell auf Bodenniveau\" title=\"Bettgestell f\u00fcr den Boden mit Tatami und Futon\" width=\"300\" height=\"164\" class=\"alignright size-medium wp-image-38813\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/boden-bett-mit-tatami-und-futon-300x164.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/boden-bett-mit-tatami-und-futon-150x82.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/boden-bett-mit-tatami-und-futon-768x420.jpg 768w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/boden-bett-mit-tatami-und-futon-1024x559.jpg 1024w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/boden-bett-mit-tatami-und-futon-441x241.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/boden-bett-mit-tatami-und-futon.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><br \/>\nWenn man sich mit dem Schlafen auf dem Boden besch\u00e4ftigt und zu diesem Thema nach Informationen sucht, landet man relativ schnell in Asien bzw. meistens direkt in Japan und liest von Begriffen wie Tatami, Futon, Shikibuton oder Kakebuton. Bekannt ist bei uns vor allem der Futon, weil es auch hierzulande eine gro\u00dfe Fangemeinde japanischer Futons gibt. Dieses ist bereits seit den 1970er\/1980er Jahren so, als insbesondere Studenten diese Art der Schlafst\u00e4tte f\u00fcr sich entdeckten.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/japan-boden-schlaf-300x200.jpg\" alt=\"Tradition Bodenschlaf in Japan - Hintergr\u00fcnde &#038; Details\" title=\"Wie und warum Japaner auf dem Boden schlafen\" width=\"300\" height=\"200\" class=\"alignright size-medium wp-image-38814\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japan-boden-schlaf-300x200.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japan-boden-schlaf-150x100.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japan-boden-schlaf-441x294.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japan-boden-schlaf.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Zur\u00fcck nach Japan: Hier verwenden etwa 50% der Bev\u00f6lkerung auch in der heutigen modernen Zeit noch traditionelle Futons, w\u00e4hrend die andere H\u00e4lfte sich abends auf westlichen Betten zur Ruhe legt. F\u00fcr die F\u00fcllung von japanischen Futons wird in der Regel fast nur Baumwolle verwendet. Der Begriff Futon umschreibt in Japan sowohl die Matratze, die man dort auch als Shikibuton kennt, als auch die von den Japanern genutzte flache Zudecke, die auch Kakebuton genannt wird. Aus diesem Grund spricht man davon, dass man sich in einen Futon hineinlegt und nicht auf einen Futon drauf.<\/p>\n<p>Futons breitet man in Japan \u00fcblicherweise auf Holzrahmen mit aufgespannten Binsenmatten aus, die als Tatami, was w\u00f6rtlich \u00fcbersetzt \u201egefaltet\u201c bedeutet, bezeichnet werden. Damit man etwas weicher und komfortabler liegt, befinden sich unter den Binsenmatten der Tatamis dicke Strohlagen. Die Japaner verwenden Tatamis als Bodenbelag und auch in hochmodernen Stadtwohnungen der heutigen Zeit gibt es in der Regel stets noch ein Zimmer, welches mit Tatami ausgelegt ist.<\/p>\n<div class=\"infokasten\">\nDer Begriff Tatami wird in Japan eigentlich f\u00fcr ein Fl\u00e4chenma\u00df verwendet und es ist durchaus \u00fcblich, dass Zimmergr\u00f6\u00dfen in Tatami angegeben werden. Das Ma\u00df ist allerdings nicht ganz einheitlich. So versteht man in Kyoto unter einem Tatami eine Fl\u00e4che von circa 1,80 m x 0,90 m, w\u00e4hrend das Ma\u00df in Tokyo etwas kleiner ausf\u00e4llt.\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/japanischer-wohnraum-mit-tatami-300x198.jpg\" alt=\"Schlaf- und Wohnraum in Japan mit Tatami ausgelegt\" title=\"Tatami in einer japanischen Wohnung\" width=\"300\" height=\"198\" class=\"alignright size-medium wp-image-38815\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japanischer-wohnraum-mit-tatami-300x198.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japanischer-wohnraum-mit-tatami-150x99.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japanischer-wohnraum-mit-tatami-441x291.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japanischer-wohnraum-mit-tatami.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Die meisten Wohnungen in Japan sind mit einem nach S\u00fcden gelegenen Balkon ausgestattet. Diesen Balkon nutzen die Japaner allerdings so gut wie gar nicht als Aufenthaltsort, er dient ihnen vielmehr unter anderem zum W\u00e4schetrocknen sowie zum Aufh\u00e4ngen der Futons. Damit der klassische japanische Futon mit reiner Baumwollf\u00fcllung trocken und \u201eflauschig\u201c bleibt, ist es n\u00e4mlich wichtig, dass er in der Sonne aufgeh\u00e4ngt wird. W\u00fcrde der Futon nicht in dieser Form \u201egepflegt\u201c, w\u00fcrde die \u00fcblicherweise in Japan vorherrschende hohe Luftfeuchtigkeit den Baumwollfuton nicht nur feucht machen, sondern die F\u00fcllung w\u00fcrde auch zusammengedr\u00fcckt und verh\u00e4rten. Derartig flachgedr\u00fcckte, mehr oder minder unbrauchbar gewordene Futons bezeichnet man als Senbei-Futons (Senbei = Reiscracker).<\/p>\n<p>Wer in Japan \u00fcber keinen S\u00fcdbalkon zum Aufh\u00e4ngen seines Futons verf\u00fcgt, kann sich seit geraumer Zeit ein technisches Hilfsmittel anschaffen, um zu verhindern, dass sich die Schlafunterlage in einen \u201eReiscracker\u201c verwandelt. Es gibt mittlerweile n\u00e4mlich so genannte Futon-Trockner, welche trockene, hei\u00dfe Luft in den Futon bl\u00e4st und so die Baumwolllagen auflockert. Futon-Trockner werden auch genutzt, um den Futon vor dem Schlafengehen vorzuw\u00e4rmen.<\/p>\n<p>Hierzulande werden Futons vielfach zusammengerollt, um ihre Weichheit zu erhalten. Diese Vorgehensweise ist in Japan nicht g\u00e4ngig. F\u00fcr die Aufbewahrung am Tage werden die Futons dort vielmehr gefaltet und in gestapelter Form in einem Wandschrank gelegt. Die Aufgabe des Faltens und Wegr\u00e4umens der in einer Wohnung genutzten Futons kommt klassisch den Frauen zu. Es soll nur wenige M\u00e4nner geben, die sich die M\u00fche machen, den eigenen Futon regelm\u00e4\u00dfig aufzuheben und in den Schrank zu packen.<\/p>\n<p>Bleiben die Futons tags\u00fcber ausgebreitet im Schlafraum liegen, werden sie von den Japanern als Mannentoko, was so viel wie 10.000-Jahre-Schlafplatz bedeutet, bezeichnet. In Japan setzt man das Liegenlassen des Futons zumeist mit Faulheit gleich. Der Zustand der Futons in der Wohnung wird zudem herangezogen, um die Hausfrauen-Qualit\u00e4ten einer Frau zu beurteilen.<\/p>\n<p><a href=\"\/bettgestelle\/futonbett\" target=\"_blank\" rel=\"noopener noreferrer\"><span class=\"malielink\"><i class=\"fa fa-long-arrow-right\"><\/i> Futonbetten bei Betten.de<\/span><\/a><\/p>\n<p>Das Schlafen auf dem Boden hat in Japan eine lange Tradition. Futons &#038; Co. geh\u00f6rten allerdings nicht schon immer dazu. Vor circa 1.000 Jahren betteten sich die Adeligen im Altertum auf faltbaren Matten zur Ruhe, die sie dazu einfach auf dem Holzfu\u00dfboden auslegten. Diese Matten k\u00f6nnen als Vorl\u00e4ufer der Tatamis angesehen werden. Die Mehrheit der Bev\u00f6lkerung konnte sich diese Form der Boden-Schlafst\u00e4tte allerdings nicht leisten. So war es f\u00fcr die einfachen Menschen auf dem Land in Japan \u00fcber Jahrhunderte hinweg \u00fcblich, gemeinsam im Familienverbund in einer Art fensterlosen Abstellkammer in der hintersten Geb\u00e4udeecke auf dem Boden \u2013 entweder Erdboden oder Holzboden \u2013 zu schlafen. Bei K\u00e4lte wurden Stroh oder trockenes Laub genutzt, um den Schlafbereich etwas angenehmer und komfortabler zu gestalten.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/japan-kimono-181x300.jpg\" alt=\"Der Kimono - traditionelle Bekleidung in Japan - aber auch Schlafunterlage und Bettdecke\" title=\"Japanische Traditionskleidung: Kimono - auch zum Schlafen verwendet\" width=\"181\" height=\"300\" class=\"alignright size-medium wp-image-38816\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japan-kimono-181x300.jpg 181w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japan-kimono-90x150.jpg 90w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/japan-kimono.jpg 386w\" sizes=\"auto, (max-width: 181px) 100vw, 181px\" \/>Nachdem ab dem 16. Jahrhundert mit dem Anbau von Baumwolle in Japan begonnen wurde, setzte es sich bei Reichen schnell durch, die kimonoartige Bekleidung f\u00fcr die kalten Monate des Jahres mit einer Baumwollf\u00fcllung versehen zu lassen. W\u00e4hrend des Tages boten diese Kimonos ihren Tr\u00e4gern einen angenehmen Schutz vor K\u00e4lte und Zugluft. Doch sie fanden auch als W\u00e4rmespender in der Nacht Verwendung \u2013 sowohl zum Zudecken als auch als isolierende, weiche Schlafunterlage. Im Laufe der Zeit entwickelten sich auf Basis dieser wattierten Kimonos die Futons. Ab dem 17. Jahrhundert verbreiteten sich diese mehr und mehr in den verschiedensten Bev\u00f6lkerungsschichten.<\/p>\n<p>Zur Lagerung des Kopfes greifen die Japaner bereits seit langer Zeit auf eine St\u00fctze zur\u00fcck, die man Makura nennt. Mit dem hier genutzten weichen Kissen mit Federf\u00fcllung oder Schaumstoff-Polster f\u00fcr den Kopf hat das fr\u00fcher verwendete Makura allerdings kaum etwas gemein. Es handelte sich dabei zumeist um ein aus Holz gefertigtes K\u00e4stchen, welches mit einer Stoffbespannung versehen war unter der sich ein leichtes Polster aus Buchweizenstreu befand. Diese Abdeckung konnte bei Bedarf entfernt bzw. gegen eine neue ersetzt werden. Insbesondere bei Frauen fielen die Makuras oft sehr hoch aus, weil diese darauf achten mussten, dass ihre Frisuren w\u00e4hrend der Nacht nicht in Mitleidenschaft gezogen wurden. Das Holzk\u00e4stchen wurde vielfach zur Aufbewahrung pers\u00f6nlicher Dinge wie Liebesbriefe verwendet. Weiterhin wurden auch h\u00e4ufig erotische Darstellungen im Makura gelagert, weshalb diese auch als Makura-Bilder bezeichnet werden.<\/p>\n<p>Die weniger gut situierten Japaner konnten \u00fcber einen langen Zeitraum die beschriebene Form des Makuras in der Regel nicht f\u00fcr sich nutzen. Sie mussten sich anderweitig behelfen und lagerten ihren Kopf deshalb meist auf einem einfachen Holzst\u00fcck oder einem Kleidungsb\u00fcndel. Sp\u00e4ter griff man zu Kissen, die mit getrockneten Halmen oder Buchweizenstreu gef\u00fcllt waren, welche auch heute noch in Japan verwendet werden, wobei eine gr\u00f6\u00dfere Auswahl an verschiedenen F\u00fcllungen zur Wahl steht. Aufgrund der vorhandenen hohen Luftfeuchtigkeit werden die hier klassischen F\u00fcllungen mit Federn und\/oder Daunen allerdings kaum genutzt.<\/p>\n<p>Tatami und Futon wurden bemerkenswerter Weise in Japan erst landesweit zum Standard, als sich das Land im Zuge der <a href=\"https:\/\/www.zeit.de\/2018\/09\/japan-kaiserreich-aufbruch-moderne-vorbild-preussen\" target=\"_blank\" rel=\"noopener noreferrer\">Meiji-Restauration<\/a> im Jahr 1868 zum Westen hin \u00f6ffnete und die Moderne Einzug hielt. Die mit der Wende neu in Japan eingef\u00fchrten Betten bzw. Bettgestelle sowie Federkernmatratzen nach westlichen Standards wurden nur sehr vereinzelt genutzt. Sie wurden vornehmlich von Bordellbetreibern angeschafft, die ihrer Klientel etwas Besonderes bieten wollten. In Privathaushalten gab es bis zum Zweiten Weltkrieg so gut wie keine westlichen Schlafsysteme. Durch die amerikanische Besatzung nach dem Krieg sowie beeinflusst durch die Hollywood-Filme wurde es in Japan dann zunehmend popul\u00e4rer ein Schlafzimmer mit einem westlichen Bett einzurichten und nicht mehr auf dem Boden zu schlafen.<\/p>\n<p>Besuchen Sie unseren Magazin-Artikel \u201e<a href=\"\/magazin\/schlafkultur-schlafen-weltweit.html\" target=\"_blank\" rel=\"noopener noreferrer\">Schlafen weltweit<\/a>\u201c, um mehr \u00fcber die <a href=\"\/magazin\/schlafkultur-schlafen-weltweit.html#schlafen-in-japan\" target=\"_blank\" rel=\"noopener noreferrer\">japanische Schlafkultur<\/a> zu erfahren.<\/p>\n<div class=\"infokasten\" style=\"background: #D1FDBE;\">\n<a href=\"\/magazin\/wp-content\/uploads\/feng-shui-zeichen-box.png\" data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\" title=\"\"><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/feng-shui-zeichen-box.png\" alt=\"Feng Shui Informationen\" width=\"150\" height=\"140\" class=\"alignright size-full wp-image-37819\" \/><\/a><\/p>\n<h3>Auf dem Boden schlafen &#038; Feng Shui<\/h3>\n<p style=\"clear: left;\">Bei einer entsprechenden Eignung der Matratze f\u00fcr die direkte Nutzung auf dem Boden spricht gem\u00e4\u00df Feng Shui nichts dagegen, den Boden als Platz zum Schlafen zu verwenden. Positiv ist dabei aus Sicht des Feng Shui, dass eine gute Erdung erreicht wird. Negativ zu bewerten ist hingegen, dass das Qi, welches sich h\u00f6her im Schlafraum befindet, \u00fcber eine bessere Qualit\u00e4t verf\u00fcgt oder anders ausgedr\u00fcckt, dass das Qi soweit unten im Zimmer schlechter ausf\u00e4llt.<\/p>\n<div class=\"clearboth\"><\/div>\n<\/div>\n<p>Lesen Sie f\u00fcr weitere Informationen unseren Magazin-Artikel \u201e<a href=\"\/magazin\/schlafzimmer-nach-feng-shui-einrichten.html\" target=\"_blank\" rel=\"noopener noreferrer\">Schlafzimmer nach Feng Shui einrichten<\/a>\u201c und dort insbesondere <a href=\"\/magazin\/schlafzimmer-nach-feng-shui-einrichten.html#matratze\" target=\"_blank\" rel=\"noopener noreferrer\">die Details zur Matratze<\/a>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/suedkorea-schlafen-boden-300x200.jpg\" alt=\"In verschiedenen L\u00e4ndern Asiens wird traditionell auf dem Boden geschlafen. Neben Japan geh\u00f6rt auch S\u00fcdkorea dazu.\" title=\"Bodenschlaf in S\u00fcdkorea\" width=\"300\" height=\"200\" class=\"alignright size-medium wp-image-38817\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/suedkorea-schlafen-boden-300x200.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/suedkorea-schlafen-boden-150x100.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/suedkorea-schlafen-boden-441x294.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/suedkorea-schlafen-boden.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Nicht nur in Japan ist das Schlafen auf dem Boden auch heute noch verbreitet. In Korea z.B. spielt sich auch das moderne Leben in den Wohnungen noch vielfach auf dem Boden ab. Dazu muss man wissen, dass es in Korea bzw. S\u00fcdkorea bereits seit mehr als 1.300 Jahren als zentrales Heizsysteme f\u00fcr Geb\u00e4ude Fu\u00dfbodenheizungen, die als Ondol bezeichnet werden, was soviel wie warmer Stein bedeutet. Da die W\u00e4rme vom Boden ausgeht, ist es nachvollziehbar, dass die Menschen gerade in den k\u00e4lteren Monaten des Jahres seine N\u00e4he suchten und es sich eingeb\u00fcrgert hat, auf dem Boden zu sitzen und zu schlafen. \u00c4hnlich wie in Japan breiten auch die auf dem Boden schlafenden Koreaner Futon-\u00e4hnliche, weichere Schlafunterlagen auf dem Steinboden aus, die tags\u00fcber wegger\u00e4umt werden.<\/p>\n<p>Da in vielen asiatischen L\u00e4ndern der Wohnraum meist sehr knapp und dementsprechend teuer ist, ist es nicht verwunderlich, dass auch heute noch vielfach auf klassischen Schlafunterlagen wie dem Futon gen\u00e4chtigt wird, die sich tags\u00fcber einfach \u201eentfernen\u201c lassen, so dass der Raum auf andere Weise genutzt werden kann. Da die Zimmer h\u00e4ufig relativ klein ausfallen, nimmt ein Bettgestell nach westlichen Standards in der Regel fast den gesamten Raum ein, so dass man es sich wirklich leisten k\u00f6nnen muss, ein Zimmer allein zum Schlafen vorzuhalten wie es bei uns \u00fcblich ist.<\/p>\n<hr>\n<p><a name=\"paleo-bodenschlaf\"><\/a><\/p>\n<h2>Paleo und Bodenschlaf<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/paleo-steinzeit-leben-300x200.jpg\" alt=\"Paleo: Lebensstil nach steinzeitlichem Vorbild\" title=\"Leben und Schlafen wie in der Steinzeit - Paleo\" width=\"300\" height=\"200\" class=\"alignright size-medium wp-image-38818\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/paleo-steinzeit-leben-300x200.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/paleo-steinzeit-leben-150x100.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/paleo-steinzeit-leben-441x294.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/paleo-steinzeit-leben.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Recherchiert man im Internet zum Thema auf dem Boden schlafen, st\u00f6\u00dft man in diesem Zusammenhang nicht nur auf die diesbez\u00fcglichen asiatischen Schlaf-Gepflogenheiten, sondern findet auch vermehrt Ergebnisse, die im Kontext mit Paleo stehen.<\/p>\n<p>Beim Paleo orientiert man sich an der Lebensweise der Menschen in der Altsteinzeit. Da diese noch keinen Zugriff auf M\u00f6belst\u00fccke und Matratzen hatten, wird ein Nachtlager in Form eines klassischen Bettsystems meist als unangemessen angesehen. Dabei geht man z.B. davon aus, dass die weiche Matratze zu komfortabel f\u00fcr den Menschen ist und ihn am korrekten Aufbau und Erhalt seiner Muskulatur w\u00e4hrend des Schlafs hindert.<\/p>\n<div class=\"infokasten\">\n<a name=\"was-ist-paleo\"><\/a><br \/>\n<strong>Exkurs: Was ist Paleo?<\/strong><\/p>\n<p style=\"clear: left;\">\nDer Ausdruck Paleo (oft auch: Pal\u00e4o) basiert auf <a href=\"https:\/\/www.3sat.de\/?source=\/nano\/glossar\/steinzeit.html\" target=\"_blank\" rel=\"noopener noreferrer\">Pal\u00e4olithikum<\/a>, wobei es sich um die fachsprachliche Bezeichnung um den urgeschichtlichen Zeitabschnitt der Altsteinzeit handelt, welche sich wiederum in drei Abschnitte (Altpal\u00e4olithikum, Mittelpal\u00e4olithikum, Jungpal\u00e4olithikum) gliedert und von etwa 2,5 Millionen bis 8000 vor Christus andauerte. Zu dieser Zeit waren die Vorfahren des modernen Menschen noch J\u00e4ger und Sammler, die von dem lebten, was die Natur ihnen anbot.<\/p>\n<p>Im Anschluss an das Pal\u00e4olithikum ver\u00e4nderte sich der Lebensstil unserer Ahnen weg vom Jagen und Sammeln hin zu Ackerbau und Viehzucht. Mit der Umstellung der Art zu leben, wurden die fr\u00fchen Menschen sesshaft und die Ern\u00e4hrung erlebte einen Wandel. So kam es unter anderem dazu, dass Milchprodukte und Getreideprodukte in den Speiseplan aufgenommen wurden.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/paleo-ernaehrung-225x300.jpg\" alt=\"Steinzeitliche Ern\u00e4hrung gem\u00e4\u00df Paleo\" title=\"Die Auswahl geeigneter Lebensmittel ist bei Paleo sehr wichtig\" width=\"225\" height=\"300\" class=\"alignright size-medium wp-image-38819\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/paleo-ernaehrung-225x300.jpg 225w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/paleo-ernaehrung-113x150.jpg 113w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/paleo-ernaehrung-441x588.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/paleo-ernaehrung.jpg 480w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/>Heutzutage steht Paleo daf\u00fcr, dass man die urspr\u00fcngliche, naturnahe Lebensweise der J\u00e4ger und Sammler aus der Altsteinzeit als Orientierung f\u00fcr die Gestaltung eines bewussten Lebens in der modernen Welt nutzt. Dabei steht insbesondere die Ern\u00e4hrung im Fokus, so dass im Rahmen von Paleo nur auf Nahrungsmittel zur\u00fcckgegriffen wird, die unseren Vorfahren bereits in dieser oder \u00e4hnlicher Form zur Verf\u00fcgung standen. Wichtig dabei sind insbesondere auch Ursprung und G\u00fcte der Nahrungsmittel. Es gilt also grob, m\u00f6glichst nat\u00fcrliche, vielf\u00e4ltige Lebensmittel auszuw\u00e4hlen und auf (stark) verarbeitete Lebensmittel zu verzichten.<\/p>\n<p>Paleo wird h\u00e4ufig mit Steinzeitk\u00fcche gleichsetzt, weil der Faktor Ern\u00e4hrung eine so starke Rolle einnimmt. Oft ist zudem auch von Paleo Di\u00e4t die Rede, weil es viele Menschen gibt, die eine Ern\u00e4hrungsumstellung nach Paleo Prinzipien vornehmen, um ihr K\u00f6rpergewicht zu reduzieren.<\/p>\n<p>Ist der Wunsch nach einer bewussteren, urspr\u00fcnglicheren Lebensart Motivation f\u00fcr die Besch\u00e4ftigung und Umsetzung von Paleo, h\u00f6rt das neue Denken in der Regel nicht im Feld der Ern\u00e4hrung auf, sondern ist weit reichender, so dass z.B. auch L\u00f6sungen f\u00fcr eine angepasste Wohnungseinrichtung angestrebt werden. In diesem Zusammenhang kommt es dann beispielsweise zu einer intensiven Auseinandersetzung mit dem Mobiliar und u.U. dazu, dass das Bett als Schlafst\u00e4tte ausgemustert und ein Lager am Boden aufgeschlagen wird.\n<\/p>\n<div class=\"clearboth\"><\/div>\n<\/div>\n<hr>\n<p><a name=\"minimalismus-bodenschlaf\"><\/a><\/p>\n<h2>Minimalismus und Bodenschlaf<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/tatami-und-futonmatratze-minimalistisch-einrichten-und-leben-300x164.jpg\" alt=\"Tatami und Futon eignen sich sehr gut f\u00fcr eine minimalistisch eingerichtete Wohnung\" title=\"Der Verzicht auf M\u00f6biliar wie ein Bett ist typisch f\u00fcr Menschen, die sich f\u00fcr den Minimalismus als Lebensstil entschieden haben.\" width=\"300\" height=\"164\" class=\"alignright size-medium wp-image-38820\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/tatami-und-futonmatratze-minimalistisch-einrichten-und-leben-300x164.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/tatami-und-futonmatratze-minimalistisch-einrichten-und-leben-150x82.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/tatami-und-futonmatratze-minimalistisch-einrichten-und-leben-768x419.jpg 768w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/tatami-und-futonmatratze-minimalistisch-einrichten-und-leben-1024x559.jpg 1024w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/tatami-und-futonmatratze-minimalistisch-einrichten-und-leben-441x241.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/tatami-und-futonmatratze-minimalistisch-einrichten-und-leben.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Das Schlafen auf dem Boden ist auch beim Minimalismus bzw. beim minimalistischen Lebensstil oder der minimalistischen Einrichtung der Wohnung ein Faktor, von dem h\u00e4ufiger zu lesen ist.<\/p>\n<p>Menschen, die sich f\u00fcr ein minimalistisch ausgerichtetes Leben entschieden haben, versuchen in der Regel nur mit dem absolut N\u00f6tigsten auszukommen. Dazu geh\u00f6rt dann meist auch ein Verzicht auf &#8222;\u00fcberfl\u00fcssiges&#8220; M\u00f6biliar, zu dem auch das Bettgestell gerechnet wird.<\/p>\n<div class=\"infokasten\">\n<a name=\"was-ist-minimalismus\"><\/a><br \/>\n<strong>Exkurs: Was ist Minimalismus?<\/strong><\/p>\n<p style=\"clear: left;\">\nUnter Minimalismus versteht man nicht nur eine Kunstrichtung der Bildenden Kunst, sondern u.a. auch einen alternativen Lebensstil. Kennzeichen des Minimalismus, welcher auch als Einfaches Leben, freiwillige Einfachheit, Simple Living oder Downshifting bezeichnet wird, ist ein Verzicht auf Konsum, um so den Zw\u00e4ngen des Alltags entgegenzuwirken und auf diese Weise mehr Selbstbestimmung und Erf\u00fcllung im Leben zur erreichen.<\/p>\n<p>Wer nach den Prinzipien des Minimalismus lebt, \u00fcberpr\u00fcft sein eigenes Verhalten bezogen auf Konsum, Besitz und Beziehungen hinsichtlich der Sinnhaftigkeit und Notwendigkeit. Es geht generell darum, so wenig wie m\u00f6glich zu besitzen und sich wirklich nur mit absolut erforderlichen Dingen zu umgeben. Zielsetzung ist dabei, sich selbst sowie auch die Umwelt nicht grundlos in irgendeiner Form zu belasten. Beim Minimalismus hat freie Zeit bzw. Freizeit einen sehr hohen Stellenwert, weshalb es nur wenig vern\u00fcnftig erscheint, einen Teil der Lebenszeit gegen Geld einzutauschen, welches man zur Anschaffung von Sachen nutzt, die man eigentlich nicht ben\u00f6tigt. Genauso sinnlos wird der Aufwand von Arbeitsstunden zur Steigerung des eigenen Ertrags, um damit den eigenen Konsum erh\u00f6hen zu k\u00f6nnen.<\/p>\n<p>F\u00fcr Minimalisten steht die selbst wahrgenommene Lebensqualit\u00e4t im Fokus, die losgel\u00f6st vom oberfl\u00e4chlichen Konsumdenken, dem Streben nach Geld und Eigentum sowie einem \u201e\u00fcbertriebenen\u201c Arbeitseinsatz sein sollte. Wie stark Verzicht ge\u00fcbt wird, f\u00e4llt individuell sehr verschieden aus, wobei es Extreme gibt, die bis hin zur Askese reichen.<\/p>\n<p>Minimalisten verzichten oft aus verschiedenen Gr\u00fcnden auf den Kauf und Unterhalt eines herk\u00f6mmlichen Bettes. Dabei kann es sowohl um den reinen Konsumverzicht als auch um die Schonung der Umwelt gehen. H\u00e4ufig werden als Alternative Schlafst\u00e4tten auf dem Boden eingerichtet.<\/p>\n<div class=\"clearboth\"><\/div>\n<\/div>\n<hr>\n<p><a name=\"schlafen-boden-gesund-ungesund\"><\/a><\/p>\n<h2>Schlafen auf dem Boden \u2013 Gesund, ungesund ?<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/frau-in-vietnam-schlaeft-auf-dem-boden-300x200.jpg\" alt=\"Frau in Vietnam schl\u00e4ft auf dem Boden im Freien\" title=\"In Asien ist es in den meisten L\u00e4ndern normal, \u00fcberall und auf dem Boden zu schlafen\" width=\"300\" height=\"200\" class=\"alignright size-medium wp-image-38821\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/frau-in-vietnam-schlaeft-auf-dem-boden-300x200.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/frau-in-vietnam-schlaeft-auf-dem-boden-150x100.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/frau-in-vietnam-schlaeft-auf-dem-boden-441x294.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/frau-in-vietnam-schlaeft-auf-dem-boden.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Wenn sehr viele Menschen aus dem asiatischen Kulturkreis, Paleoanh\u00e4nger und \u00fcberzeugte Minimalisten auf den Bodenschlaf schw\u00f6ren bzw. ihn ohne konkret definierbare Folgen praktizieren, kann es daran doch eigentlich nichts auszusetzen geben, oder? Also m\u00fcsste dementsprechend die Hauptfragestellung unseres Artikels \u201eSchlafen auf dem Boden \u2013 Gesund, ungesund ?\u201c schlicht und einfach mit \u201eGesund\u201c zu beantworten sein. So leicht sollte man es sich jedoch nicht machen.<\/p>\n<p>F\u00fcr unser Verst\u00e4ndnis muss der Bodenschlaf sehr viel differenzierter betrachtet werden. Aus diesem Grund haben wir die verschiedensten Argumente f\u00fcr und gegen das Schlafen auf dem Boden zusammengetragen, kritisch \u00fcberpr\u00fcft und die Ergebnisse nachfolgend f\u00fcr Sie zusammengefasst.<\/p>\n<p><a name=\"schlafen-boden-gesund\"><\/a><\/p>\n<h3>These: \u201eSchlafen auf dem Boden ist gesund\u201c \u2013 Pro-Argumente<\/h3>\n<ol>\n<li><strong>Moderne Matratzen sind zu weich und bequem. Man bewegt sich zu wenig.<\/strong><\/li>\n<li><strong>Es ist nat\u00fcrlich auf dem Boden zu schlafen und der K\u00f6rper passt sich entsprechend an.<\/strong><\/li>\n<li><strong>Man bleibt beweglicher.<\/strong><br \/>\nBetten bzw. Bettgestelle erlauben uns in Abh\u00e4ngigkeit von ihrer Konstruktion einen sehr bequemen Ein- und Ausstieg. Wer auf dem Boden schl\u00e4ft, legt sich hingegen \u00e4hnlich wie die meisten Tiere zu Ruhe. Man kann sich nat\u00fcrlich einfach fallen lassen oder man begibt sich zun\u00e4chst in eine kniende Position &#8222;krabbelt&#8220; an die gew\u00fcnschte Stelle und streckt sich dann aus. Um nach dem Schlafen wieder in die aufrechte Position zu gelangen, ist auch wesentlich mehr Anstrengung n\u00f6tig.<\/li>\n<\/ol>\n<h3>Weitere Argumente f\u00fcr den Bodenschlaf, die h\u00e4ufiger genannt werden:<\/h3>\n<p><strong>Geldersparnis<\/strong><br \/>\nKeine Kosten f\u00fcr ein Bettgestell, vielfach auch keine Kosten f\u00fcr eine Unterfederung und teilweise auch keine Kosten f\u00fcr eine Matratze. \u2013 Abh\u00e4ngig davon, wie die Schlafst\u00e4tte am Boden gestaltet wird bzw. welche Art von Schlafunterlage genutzt wird. Alternativ zu Matratzen und Futons kommen beispielsweise h\u00e4ufig Gymnastik- und Yogamatten, Oberbetten\/Bettdecken oder Wolldecken zum Einsatz. Man braucht auch keinen Nachttisch, da man die Bodenfl\u00e4che als Ablage nutzen kann (siehe auch nachfolgendes Argument: Mehr Platz)<\/p>\n<p><strong>Mehr Platz &#038; ggf. Raum multifunktionaler verwendbar<\/strong><br \/>\nBettgestelle nehmen durchaus einiges an Fl\u00e4che im Schlafzimmer ein und sie lassen sich (abgesehen vom Klappbett) nicht mal eben zur Seite stellen oder abbauen, wenn die Fl\u00e4che im Raum anderweitig genutzt werden soll. Wenn man seinen Schlafplatz am Boden flexibel durch die Auslage eines klappbaren Futons oder von Matten gestaltet, kann man das Nachtlager bei Bedarf schnell und einfach vollst\u00e4ndig \u201everschwinden\u201c lassen. Ebenfalls unter die Argumentation \u201emehr Platz\u201c f\u00e4llt auch der Aspekt, dass man beim Schlafen in Bodenn\u00e4he die komplette Fl\u00e4che neben der Lagerstatt als Ablagefl\u00e4che nutzen kann, so dass man viel mehr Dinge griffbereit neben seinem \u201eBodenbett\u201c als auf einem klassischen Nachttisch.<\/p>\n<p><strong>Kaum Fallh\u00f6he &#8211; kein Verletzungsrisiko<\/strong><br \/>\nIm Gegensatz zu herk\u00f6mmlichen Bettgestellen gibt es bei einem bodennahen Schlafplatz kein Fallrisiko bzw. es besteht keine Gefahr des Herausfallens. Dieser Aspekt bewegt z.B. h\u00e4ufig Eltern dazu, ihre Kinder einfach mit Matratze auf dem Boden schlafen zu lassen. Es soll aber auch erwachsene Personen geben, die sehr unruhig schlafen und so nachts h\u00e4ufiger aus dem Bett st\u00fcrzen.<\/p>\n<p><strong>Aufstehen soll leichter fallen<\/strong><br \/>\nSchl\u00e4ft man auf dem Boden, soll der K\u00f6rper automatisch alarmbereiter &#8211; also wacher &#8211; bleiben. Aus diesem Grund soll das morgendliche Aufstehen beim Bodenschlaf leichter im Vergleich zum Schlafen im h\u00f6heren Bett gelingen.<\/p>\n<p><strong>Flexibilit\u00e4t &#038; Freiheit<\/strong><br \/>\nWenn man sich daran gew\u00f6hnt hat, auf dem Boden zu schlafen bzw. wenn man nicht mehr darauf angewiesen ist, in einem regul\u00e4ren Bettsystem mit Matratze zu n\u00e4chtigen, kann man quasi flexibel \u00fcberall \u00fcbernachten, wo man will. Man ist komplett frei, sowohl bei der Wahl des Schlafplatzes in der Wohnung (heute lieber am Fenster oder an der Heizung) als auch au\u00dferhalb der Wohnung.<\/p>\n<div class=\"infokasten\" style=\"background: #FFF8E4;\">\n<a name=\"bequem-erholsam-liegen\"><\/a><\/p>\n<h3>Exkurs: Bequem und erholsames Liegen<\/h3>\n<p style=\"clear: left;\">\n<img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/bequem-und-erholsam-liegen-441x241.jpg\" alt=\"Erholsam und bequem liegen erfordert St\u00fctzung und Nachgeben in bestimmten Bereichen der Schlafunterlage\" title=\"Bequem liegen und erholsam schlafen auf geeigneter Unterlage\" width=\"441\" height=\"241\" class=\"alignright size-nexttonavi wp-image-38822\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bequem-und-erholsam-liegen-441x241.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bequem-und-erholsam-liegen-150x82.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bequem-und-erholsam-liegen-300x164.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bequem-und-erholsam-liegen-768x420.jpg 768w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bequem-und-erholsam-liegen-1024x559.jpg 1024w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bequem-und-erholsam-liegen.jpg 1600w\" sizes=\"auto, (max-width: 441px) 100vw, 441px\" \/>Damit wir bequem und erholsam liegen k\u00f6nnen, sind wir auf eine flexible Unterlage angewiesen, die ein Einsinken der H\u00fcfte erm\u00f6glicht und gleichzeitig ausreichend Widerstand von unten f\u00fcr die St\u00fctzung der Taille bietet.<\/p>\n<p>In R\u00fcckenlage ist eine gute Gegenst\u00fctzung der Wirbels\u00e4ule erforderlich und gleichzeitig darf das Becken nicht durchh\u00e4ngen bzw. zu tief in die Unterlage einsinken. Der Kopf sollte beim Liegen auf dem R\u00fccken nicht so hoch wie in seitlicher Liegeposition gebettet werden.<\/p>\n<p>Wenn man auf dem Bauch liegt, ist es wichtig, dass die Schlafunterlage im Bereich der Lendenwirbels\u00e4ule ausreichend Widerstand bzw. Unterst\u00fctzung bietet. Wird die Lendenwirbels\u00e4ule bei Bauchlage nicht gen\u00fcgend gest\u00fctzt, kommt es zum Hohlkreuz. Beim Liegen auf dem Bauch sollte man idealerweise auf ein Kissen verzichten, ist dieses nicht m\u00f6glich, sollte man sich f\u00fcr ein m\u00f6glichst flaches Produkt entscheiden.<\/p>\n<p>Wir gehen heute oft davon aus, dass es sich bei R\u00fcckenschmerzen um ein Ph\u00e4nomen unserer modernen Welt und Lebensweise handelt. Es ist allerdings so, dass die Wissenschaft durch das R\u00f6ntgen von \u00e4gyptischen Mumien herausgefunden hat, dass auch diese bereits unter R\u00fcckenerkrankungen zu leiden hatten. Nichtsdestotrotz hat es den Anschein, als wenn R\u00fcckenschmerzen, die w\u00e4hrend oder im Anschluss an das n\u00e4chtliche Liegen in Erscheinung treten, zugenommen haben, seit wir am Tage nicht mehr so hart k\u00f6rperlich arbeiten und die Muskulatur nicht mehr in identischem Ma\u00dfe ausgebildet und trainiert ist wie das noch vor wenigen Generationen beim Gros der Bev\u00f6lkerung festzustellen war. Die Menschen waren fr\u00fcher im Durchschnitt kleiner und da es weniger \u00dcberern\u00e4hrung gab, fielen auch die Dimensionen des K\u00f6rpers ingesamt wesentlich vorteilhafter f\u00fcr das Wohl der Wirbels\u00e4ule aus. Verh\u00e4ltnism\u00e4\u00dfig betrachtet, waren Haltungssch\u00e4den und die damit verbundenen Folgeleiden wesentlich weniger verbreitet.<\/p>\n<p>Unsere Rumpfhaltemuskulatur ist tags\u00fcber besonders hohen Belastungen ausgesetzt, was sich auf die Gestaltung unseres Nachtlagers auswirkt. Ein zentraler Punkt dabei ist die notwendige Entlastung der Bandscheiben w\u00e4hrend der Nacht. Befindet sich der K\u00f6rper in horizontaler Position, k\u00f6nnen sich die Bandscheiben ausdehnen. Zudem sollten sich s\u00e4mtliche Partien des K\u00f6rpers, die an Bewegungen beteiligt sind, w\u00e4hrend der Nacht entspannen k\u00f6nnen. Dieses trifft in besonderem Ma\u00dfe auf die Muskulatur zu.<\/p>\n<p>In R\u00fccken- und Seitenlage sollte die Wirbels\u00e4ule so gelagert werden, dass ihre Form ann\u00e4hernd der in stehender Position entspricht (&#8222;nat\u00fcrliche Doppel-S-Form&#8220;. Alle Knochen der Wirbels\u00e4ule sind dabei &#8222;lotrecht&#8220; \u00fcbereinander angeordnet. Aufgrund abweichender Kr\u00e4fteeinwirkung im Liegen l\u00e4sst sich eine ganz exakte Wirbels\u00e4ulenlagerung nicht erreichen, aber eine hohe Ann\u00e4herung daran ist m\u00f6glich.<\/p>\n<p>Die ideale Schlafunterlage ist &#8211; unabh\u00e4ngig, ob im Bett oder am Boden &#8211; weder zu weich noch zu hart. Ein zu weiches Lager erkennt man daran, dass der R\u00fccken durchh\u00e4ngt oder man einen unangenehmen Druck im Bereich der Schultern oder H\u00fcfte wahrnimmt. Zu hart ist die Schlafunterlage, wenn man auf dem R\u00fccken oder auf der Seite liegt und man noch ohne Probleme eine flache Hand zwischen Matratze und Taille durchschieben kann.<\/p>\n<div class=\"clearboth\"><\/div>\n<\/div>\n<p><a name=\"schlafen-boden-ungesund\"><\/a><\/p>\n<h3>These: \u201eSchlafen auf dem Boden ist ungesund\u201c \u2013 Contra-Argumente<\/h3>\n<ol>\n<li><strong>Der Boden ist als Schlafunterlage zu hart und gibt zu wenig nach.<\/strong><br \/>\nWer auf einem Boden aus Beton liegt, liegt auf einer Fl\u00e4che, die noch weniger als ein ung\u00fcnstig gew\u00e4hlter Lattenrost oder das ber\u00fchmte Brett im Bett nachgibt.<\/li>\n<li><strong>Die Matratze am Boden kann nicht atmen. Es besteht Schimmelgefahr.<\/strong><br \/>\nWenn eine Matratze direkt auf dem Boden aufliegt, kann die von der Matratze aufgenommene Feuchtigkeit, nicht entweichen bzw. bildet sich unter der Matratze Feuchtigkeit. Wenn die Matratze nicht regelm\u00e4\u00dfig aufgestellt wird, kann dieses zur Entstehung von ungesundem Schimmel f\u00fchren.<\/li>\n<li><strong>Ein- und Ausstieg ins Bett fallen k\u00f6rperlich schwerer.<\/strong><br \/>\nMan muss sich deutlich mehr anstrengen, um ins Bett zu kommen und wieder heraus zu gelangen. (Kann man auch positiv bewerten, s.o.)<\/li>\n<li><strong>In Bodenn\u00e4he ist es dreckiger, da sich dort mehr Hausstaub als in h\u00f6heren Lagen im Raum befindet.<\/strong><\/li>\n<li><strong>Am Boden ist es meist k\u00e4lter und es kann Zugluft vorhanden sein.<\/strong><\/li>\n<li><strong>Die Luft ist schlechter.<\/strong><br \/>\nDas Kohlendioxid aus der Atemluft konzentriert sich ebenso wie ins Haus eingedrungene Abgase oder die Absonderungen von Rauchern am Boden, weshalb die Luftqualit\u00e4t dort schlechter ausf\u00e4llt.<\/li>\n<li><strong>Die Auswirkungen der Erdstrahlung sind deutlich h\u00f6her.<\/strong><\/li>\n<\/ol>\n<h3>Weitere Argumente gegen den Bodenschlaf, die h\u00e4ufiger genannt werden:<\/h3>\n<p><strong>Reduziertes Sicherheitsempfinden<\/strong><br \/>\nAm Boden f\u00fchlt man sich (unbewusst) weniger sicher als in erh\u00f6hter Position. Man hat weniger \u00dcberblick im Raum.<\/p>\n<hr>\n<p><a name=\"auf-dem-boden-schlafen-studien\"><\/a><\/p>\n<h2>Studien: Auf dem Boden schlafen<\/h2>\n<p>Vorweg ist festzustellen, dass es keine richtigen Studien zum Schlafen auf dem Boden gibt. Es gibt allerdings verschiedene Untersuchungen und Studien, aus denen sich R\u00fcckschl\u00fcsse in Bezug auf den Bodenschlaf ziehen lassen.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/schlafen-gorilla-auf-dem-boden-seitlich-300x209.jpg\" alt=\"Auf dem Boden schlafender Gorilla in nat\u00fcrlicher Schlafhaltung mit Schutzfunktionen\" title=\"Gorilla schl\u00e4ft auf dem Boden in nat\u00fcrlicher Schlaflage\" width=\"300\" height=\"209\" class=\"alignright size-medium wp-image-38823\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/schlafen-gorilla-auf-dem-boden-seitlich-300x209.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/schlafen-gorilla-auf-dem-boden-seitlich-150x105.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/schlafen-gorilla-auf-dem-boden-seitlich-441x307.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/schlafen-gorilla-auf-dem-boden-seitlich.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Unter <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC1119282\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC1119282\/<\/a> finden Sie einen englischsprachigen Artikel des Physiotherapeuten Michael Tetley, der sich mit instinktiv eingenommenen Schlaf- und Ruhepositionen befasst und diese als Ansatzpunkt f\u00fcr die Behandlung von R\u00fccken- und Gelenkschmerzen sieht. Diese Erkenntnisse beruhen unter anderem auf der Beobachtung anderer Primaten hinsichtlich ihrer Schlafgewohnheiten und deren Analyse.<\/p>\n<p>In der Schweiz wurde eine Nationalfonds-Studie vom Institut f\u00fcr Pflege von der Z\u00fcricher Hochschule f\u00fcr angewandte Wissenschaften (ZHAW) und der Klinik Valens durchgef\u00fchrt. An dieser Studie waren 140 Patienten mit Hirnschlag und Multipler Sklerose beteiligt. Grob ging es darum, herauszufinden, wie sich eine Pflege am Boden statt einer Pflege im Bett auswirkt. Die Patienten\/innen wurden dazu auf Matratze und Bettrost am Boden gelagert. Die Ergebnisse der Studie fielen sehr positiv aus und es konnte eine Verbesserung von Beweglichkeit und Gleichgewicht bei den Patienten\/innen erreicht werden.<\/p>\n<p>D\u00e4nische Forscher haben im Fachmagazin &#8222;Spine&#8220; Ergebnisse einer Untersuchung ver\u00f6ffentlicht, bei der es um geeignete Schlafunterlagen f\u00fcr Menschen mit Schmerzen im Bereich der Lendenwirbels\u00e4ule ging. Verglichen wurdendabei Wasserbett, Schaumstoffmatratze und Futon. Dabei sollen die weicheren Schlaflager (Wasserbett und Schaummatratze) f\u00fcr einen l\u00e4ngeren Schlaf mit weniger Beschwerden gesorgt haben. Auf dem harten Futon fiel der Schlaf k\u00fcrzer und mit mehr Beschwerden behaftet aus, wobei die Unterschiede letzten Endes nicht ganz so gravierend ausgefallen sein sollen (etwas weniger Schmerzen, 1 Stunde < mehr Schlaf). Weiterhin lie\u00df sich nicht kl\u00e4ren, ob die reduzierten Schmerzen zum l\u00e4ngeren Schlaf oder der l\u00e4ngere Schlaf zur Schmerzreduzierung f\u00fchrte (<a href=\"https:\/\/www.welt.de\/gesundheit\/article1876762\/Schlaf-Weiche-Matratzen-helfen-gegen-Rueckenschmerzen.html\" target=\"_blank\" rel=\"noopener noreferrer\">Welche Matratzen helfen gegen R\u00fcckenschmerzen? | Welt.de<\/a>).<\/p>\n<p>Die weit herrschende Meinung, dass man gerade bei R\u00fcckenproblemen am besten auf einer m\u00f6glichst harten Schlafunterlage aufgehoben ist, wurde bereits 2003 in einer spanischen Studie mit 313 Patienten\/innen widerlegt. Im Ergebnis haben die meisten Probanden auf einer mittelharten Matratze am besten geschlafen. Infos hierzu auf: <a href=\"https:\/\/rp-online.de\/leben\/gesundheit\/medizin\/rueckenschmerzen\/rueckenschmerzen-welche-matratze-ist-die-beste_aid-16727649\" target=\"_blank\" rel=\"noopener noreferrer\">RP-Online.de<\/a> und <a href=\"https:\/\/www.aerzteblatt.de\/archiv\/wer-sich-nicht-zu-hart-bettet-liegt-besser-7ac07cfe-405e-4775-bf25-e827fd1ef6a9\" target=\"_blank\" rel=\"noopener noreferrer\">Aerzteblatt.de<\/a><\/p>\n<p><a name=\"tipps-auf-boden-schlafen\"><\/a><\/p>\n<h2>Tipps: Auf dem Boden schlafen<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/bodenschlaf-nachtlager-am-boden-300x169.jpg\" alt=\"Tipps zum Schlafen auf dem Boden\" title=\"Auf dem Boden schlafen - Tipps (copyright by: XtravaganT | Fotolia.com)\" width=\"300\" height=\"169\" class=\"alignright size-medium wp-image-38824\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bodenschlaf-nachtlager-am-boden-300x169.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bodenschlaf-nachtlager-am-boden-150x84.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bodenschlaf-nachtlager-am-boden-435x245.jpg 435w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bodenschlaf-nachtlager-am-boden-441x248.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/bodenschlaf-nachtlager-am-boden.jpg 462w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Wie Sie aus dem vorangegangen Abschnitt dieses Artikels \u201eSchlafen auf dem Boden \u2013 Gesund, ungesund?\u201c ableiten konnten, handelt es sich beim Liegen und Schlafen um sehr subjektive Angelegenheiten. Niemand wird Ihnen so ohne weiteres sagen k\u00f6nnen, ob es f\u00fcr Sie besser oder schlechter ist, auf dem Boden zu schlafen. Genau wie bei der Wahl einer Matratze f\u00fchrt auch beim Bodenschlaf kaum ein Weg an einem Test bzw. Probeliegen vorbei. Damit Ihr Einstieg in die \u201etiefer\u201c gelegene Schlafwelt optimal gelingt, haben wir Ihnen einige Tipps zum Schlafen auf dem Boden zusammengestellt:<\/p>\n<h3>Fangen Sie langsam mit der Umstellung an<\/h3>\n<p>Nehmen Sie Ihre Matratze aus dem Bett und legen Sie sie neben das Bett auf den Boden. Wenn Sie noch langsamer beginnen m\u00f6chten, nehmen Sie auch den Lattenrost heraus, platzieren Sie diesen auf den Boden und legen Sie dann die Matratze auf. Auf diese Weise k\u00f6nnen Sie erste Erfahrungen machen und z.B. feststellen wie der Liegekomfort Ihrer Matratze ohne Unterfederung (bei Verzicht auf den Lattenrost) ausf\u00e4llt, wie sie mit dem reduzierten Einstieg in ihre sowie reduziertem Ausstieg aus Ihrer Schlafst\u00e4tte zurecht kommen, wie Sie mit der ver\u00e4nderten Perspektive zurechtkommen oder wie es um Temperatur und Luftqualit\u00e4t in Bodenn\u00e4he in Ihrem Schlafraum bestellt ist.<\/p>\n<h3>Planen Sie etwas Zeit ein<\/h3>\n<p>Wenn man sich mit Erfahrungsberichten zum Schlafen auf dem Boden besch\u00e4ftigt, liest man h\u00e4ufig, dass es dauert, bis der K\u00f6rper sich vom Bett auf den Boden umstellt. Damit zusammenh\u00e4ngend sind oft Schmerzen und ein eher unruhiger Schlaf in den ersten N\u00e4chten des Schlafens auf dem Boden verbunden. Sollten Sie also ernsthaft auf ein Nachtlager am Boden umstellen wollen, sollten Sie nicht davon ausgehen, dass sie nach zwei Tagen am Boden wie ein Baby schlafen werden. Stellen Sie sich mental darauf ein, dass es einige N\u00e4chte oder auch mehrere brauchen wird, bis Sie ganz genau einsch\u00e4tzen k\u00f6nnen, ob Sie vom Bodenschlaf profitieren oder nicht.<\/p>\n<h3>Pflegen Sie Ihr Nachtlager<\/h3>\n<p>Matratzen sind generell viel Feuchtigkeit ausgesetzt, die wieder entweichen k\u00f6nnen muss. Dieses ist bei einer direkt auf dem Boden aufliegenden Matratze aufgrund der mangelnden Bel\u00fcftung unzureichend bis gar nicht m\u00f6glich. Aus diesem Grund sollten Sie die Matratze regelm\u00e4\u00dfig ausl\u00fcften bzw. abtrocknen lassen, in dem Sie sie aufrecht hinstellen. Gleiches gilt nat\u00fcrlich auch f\u00fcr einen Futon. Lesen Sie hierzu auch unsere Artikel: <a href=\"\/magazin\/wie-reinige-ich-meine-matratze-richtig.html\" target=\"_blank\" rel=\"noopener noreferrer\">Wie reinige ich meine Matratze richtig?<\/a> und <a href=\"\/magazin\/warum-schwitzen-wir-beim-schlafen.html\" target=\"_blank\" rel=\"noopener noreferrer\">Warum schwitzen wir beim Schlafen<\/a><\/p>\n<hr>\n<p><a name=\"schlafen-auf-boden-fazit\"><\/a><\/p>\n<h2>Fazit zum Schlafen auf dem Boden<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"\/magazin\/wp-content\/uploads\/natur-auf-dem-boden-liegen-rasen-300x225.jpg\" alt=\"Wer sich auf dem Boden liegend und schlafend wohlf\u00fchlt, sollte dieses auch tun.\" title=\"In der Natur auf dem Boden liegen und schlafen\" width=\"300\" height=\"225\" class=\"alignright size-medium wp-image-38825\" srcset=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/natur-auf-dem-boden-liegen-rasen-300x225.jpg 300w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/natur-auf-dem-boden-liegen-rasen-150x113.jpg 150w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/natur-auf-dem-boden-liegen-rasen-441x331.jpg 441w, https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/natur-auf-dem-boden-liegen-rasen.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Liegen und Schlafen werden stets sehr subjektiv wahrgenommen, betrachtet und beurteilt. Aus diesem Grund steht es niemandem zu, \u00fcber einen anderen zu urteilen, der ein Nachtlager gew\u00e4hlt hat, welches so gar nicht den eigenen Vorstellungen entspricht. Was f\u00fcr den einen gut ist, muss f\u00fcr den anderen nicht gut sein.<\/p>\n<p>Dass Menschen hierzulande, die sich bewusst f\u00fcr eine Schlafst\u00e4tte am Boden entscheiden, oftmals mit viel Kritik aus ihrem Umfeld umgehen m\u00fcssen, ist nicht gerechtfertigt und unangemessen. Die meisten Personen, die Kritik daran \u00fcben, dass am Boden geschlafen wird, haben dieses selbst noch nie ausprobiert und selbst wenn, wenn es f\u00fcr sie nicht gepasst hat, k\u00f6nnen sie daraus nicht pauschal ableiten, dass es f\u00fcr alle nicht passt.<\/p>\n<p>Als Pro-Argument f\u00fcr den Bodenschlaf wird oft genannt, dass die Japaner oder auch allgemeiner die Asiaten ja bereits seit Jahrhunderten auf dem Boden ihr Nachtlager aufschlagen, weshalb damit ja nichts Sch\u00e4dliches verbunden sein kann. Diesen Sachverhalt muss man allerdings differenzierter sehen und ber\u00fccksichtigen, dass die Japaner bzw. Asiaten k\u00f6rperlich meist ganz anders als wir konstituiert sind, auf wesentlich weicheren B\u00f6den als bei uns im Standard liegen und dass sie es in der Regel von Kindesbeinen an, gew\u00f6hnt sind, auf dem Boden zu liegen. Pauschal kann man daraus also nicht herleiten, was der Japaner kann, kann ich auch&#8230;<\/p>\n<p>Wer sich gut vorstellen kann auf dem Boden zu schlafen, aus welchen Gr\u00fcnden auch immer, sollte dieses ausprobieren und sich ein konkretes Bild davon machen, wie sich der Wechsel des Nachtlagers auf seinen individuellen Schlaf und sein pers\u00f6nliches Wohlbefinden auswirkt.<\/p>\n<p>Grunds\u00e4tzlich sollten man allerdings bedenken, dass sich Schlafen auf dem Boden bzw. auf einer harten Unterlage nicht gleicherma\u00dfen gut f\u00fcr alle Menschen anbietet. Dabei spielen viele Faktoren eine Rolle, wobei unter anderem der eigene K\u00f6rper bzw. der eigene K\u00f6rpertyp (siehe hierzu im Magazin: <a href=\"\/magazin\/koerpergerechte-betten-worauf-achten.html\" target=\"_blank\" rel=\"noopener noreferrer\">K\u00f6rpergerechte Betten<\/a>), die tats\u00e4chlich gew\u00e4hlte Schlafunterlage (Matratze, Futon, Yogamatte, Bettdecke&#8230;) und der pers\u00f6nliche Gesundheitszustand (R\u00fcckenleiden, Schulterschmerzen, starke Muskulatur, schwache Muskulatur, Skeletterkrankungen) von gro\u00dfer Bedeutung sind.<\/p>\n<hr>\n","protected":false},"excerpt":{"rendered":"<p>Das Schlafen auf dem Boden ist in unseren Breiten weitgehend verp\u00f6nt. Traditionell verwurzelt ist der Verzicht auf ein regul\u00e4res Bettgestell in Asien wie z.B. in Japan oder Korea. Unter anderem im Zuge von Paleo und minimalistischer Lebensweise r\u00fcckt der Bodenschlaf auch hierzulande st\u00e4rker in den Fokus.<\/p>\n","protected":false},"author":14,"featured_media":38768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[153,156,157,158],"tags":[],"class_list":["post-38811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-schlafen","category-schlaftipps","category-schlafzimmer","category-produkt-news-neu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schlafen auf dem Boden - gesund oder ungesund? Worauf dabei achten?<\/title>\n<meta name=\"description\" content=\"Wie gesund ist es auf dem Boden zu schlafen? Ist es Bodenschlaf sogar ungesund? Warum schlafen Japaner auf dem Boden? Wie h\u00e4ngt das Schlafen auf dem Boden mit Paleo oder Minimalismus zusammen? Diesen und weiteren Fragen gehen wir im Schlafmagazin online auf den Grund. Zudem u.a. Tipps zum Schlafen auf dem Boden.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schlafen auf dem Boden - gesund oder ungesund? Worauf dabei achten?\" \/>\n<meta property=\"og:description\" content=\"Wie gesund ist es auf dem Boden zu schlafen? Ist es Bodenschlaf sogar ungesund? Warum schlafen Japaner auf dem Boden? Wie h\u00e4ngt das Schlafen auf dem Boden mit Paleo oder Minimalismus zusammen? Diesen und weiteren Fragen gehen wir im Schlafmagazin online auf den Grund. Zudem u.a. Tipps zum Schlafen auf dem Boden.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-30T15:17:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-01T08:19:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"424\" \/>\n\t<meta property=\"og:image:height\" content=\"283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ulrich Carsten\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ulrich Carsten\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"30\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html\"},\"author\":{\"name\":\"Ulrich Carsten\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/person\\\/7c1a4c0500ca2b101723693361b5750d\"},\"headline\":\"Schlafen auf dem Boden &#8211; Gesund, ungesund?\",\"datePublished\":\"2018-04-30T15:17:18+00:00\",\"dateModified\":\"2025-12-01T08:19:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html\"},\"wordCount\":5079,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/auf-dem-boden-schlafen-gesund-ungesund.jpg\",\"articleSection\":[\"Schlafen\",\"Schlaftipps\",\"Schlafumgebung\",\"Schlafzimmer\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html\",\"name\":\"Schlafen auf dem Boden - gesund oder ungesund? Worauf dabei achten?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/auf-dem-boden-schlafen-gesund-ungesund.jpg\",\"datePublished\":\"2018-04-30T15:17:18+00:00\",\"dateModified\":\"2025-12-01T08:19:48+00:00\",\"description\":\"Wie gesund ist es auf dem Boden zu schlafen? Ist es Bodenschlaf sogar ungesund? Warum schlafen Japaner auf dem Boden? Wie h\u00e4ngt das Schlafen auf dem Boden mit Paleo oder Minimalismus zusammen? Diesen und weiteren Fragen gehen wir im Schlafmagazin online auf den Grund. Zudem u.a. Tipps zum Schlafen auf dem Boden.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html#primaryimage\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/auf-dem-boden-schlafen-gesund-ungesund.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/auf-dem-boden-schlafen-gesund-ungesund.jpg\",\"width\":424,\"height\":283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/schlafen-auf-dem-boden-gesund-ungesund.html#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.betten.at\\\/magazin\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schlafen auf dem Boden &#8211; Gesund, ungesund?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/\",\"name\":\"\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#organization\",\"name\":\"Betten.de\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/logo-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/logo-1-1.jpg\",\"width\":500,\"height\":500,\"caption\":\"Betten.de\"},\"image\":{\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/#\\\/schema\\\/person\\\/7c1a4c0500ca2b101723693361b5750d\",\"name\":\"Ulrich Carsten\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/wp-content\\\/uploads\\\/ucarsten-l-96x96.jpg\",\"caption\":\"Ulrich Carsten\"},\"description\":\"Zertifizierter Bettenfachberater mit dem Schwerpunkt Matratzen in unserem Online-Shop Betten.de und seit 2011 Chef-Redakteur im Betten.de-Schlafmagazin.\",\"url\":\"https:\\\/\\\/www.betten.de\\\/magazin\\\/author\\\/admin\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schlafen auf dem Boden - gesund oder ungesund? Worauf dabei achten?","description":"Wie gesund ist es auf dem Boden zu schlafen? Ist es Bodenschlaf sogar ungesund? Warum schlafen Japaner auf dem Boden? Wie h\u00e4ngt das Schlafen auf dem Boden mit Paleo oder Minimalismus zusammen? Diesen und weiteren Fragen gehen wir im Schlafmagazin online auf den Grund. Zudem u.a. Tipps zum Schlafen auf dem Boden.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html","og_locale":"de_DE","og_type":"article","og_title":"Schlafen auf dem Boden - gesund oder ungesund? Worauf dabei achten?","og_description":"Wie gesund ist es auf dem Boden zu schlafen? Ist es Bodenschlaf sogar ungesund? Warum schlafen Japaner auf dem Boden? Wie h\u00e4ngt das Schlafen auf dem Boden mit Paleo oder Minimalismus zusammen? Diesen und weiteren Fragen gehen wir im Schlafmagazin online auf den Grund. Zudem u.a. Tipps zum Schlafen auf dem Boden.","og_url":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html","article_published_time":"2018-04-30T15:17:18+00:00","article_modified_time":"2025-12-01T08:19:48+00:00","og_image":[{"width":424,"height":283,"url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund.jpg","type":"image\/jpeg"}],"author":"Ulrich Carsten","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Ulrich Carsten","Gesch\u00e4tzte Lesezeit":"30\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html#article","isPartOf":{"@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html"},"author":{"name":"Ulrich Carsten","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/person\/7c1a4c0500ca2b101723693361b5750d"},"headline":"Schlafen auf dem Boden &#8211; Gesund, ungesund?","datePublished":"2018-04-30T15:17:18+00:00","dateModified":"2025-12-01T08:19:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html"},"wordCount":5079,"commentCount":0,"publisher":{"@id":"https:\/\/www.betten.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html#primaryimage"},"thumbnailUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund.jpg","articleSection":["Schlafen","Schlaftipps","Schlafumgebung","Schlafzimmer"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html","url":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html","name":"Schlafen auf dem Boden - gesund oder ungesund? Worauf dabei achten?","isPartOf":{"@id":"https:\/\/www.betten.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html#primaryimage"},"image":{"@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html#primaryimage"},"thumbnailUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund.jpg","datePublished":"2018-04-30T15:17:18+00:00","dateModified":"2025-12-01T08:19:48+00:00","description":"Wie gesund ist es auf dem Boden zu schlafen? Ist es Bodenschlaf sogar ungesund? Warum schlafen Japaner auf dem Boden? Wie h\u00e4ngt das Schlafen auf dem Boden mit Paleo oder Minimalismus zusammen? Diesen und weiteren Fragen gehen wir im Schlafmagazin online auf den Grund. Zudem u.a. Tipps zum Schlafen auf dem Boden.","breadcrumb":{"@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html#primaryimage","url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund.jpg","contentUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/auf-dem-boden-schlafen-gesund-ungesund.jpg","width":424,"height":283},{"@type":"BreadcrumbList","@id":"https:\/\/www.betten.de\/magazin\/schlafen-auf-dem-boden-gesund-ungesund.html#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.betten.at\/magazin"},{"@type":"ListItem","position":2,"name":"Schlafen auf dem Boden &#8211; Gesund, ungesund?"}]},{"@type":"WebSite","@id":"https:\/\/www.betten.de\/magazin\/#website","url":"https:\/\/www.betten.de\/magazin\/","name":"","description":"","publisher":{"@id":"https:\/\/www.betten.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.betten.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.betten.de\/magazin\/#organization","name":"Betten.de","url":"https:\/\/www.betten.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/logo-1-1.jpg","contentUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/logo-1-1.jpg","width":500,"height":500,"caption":"Betten.de"},"image":{"@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.betten.de\/magazin\/#\/schema\/person\/7c1a4c0500ca2b101723693361b5750d","name":"Ulrich Carsten","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","url":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","contentUrl":"https:\/\/www.betten.de\/magazin\/wp-content\/uploads\/ucarsten-l-96x96.jpg","caption":"Ulrich Carsten"},"description":"Zertifizierter Bettenfachberater mit dem Schwerpunkt Matratzen in unserem Online-Shop Betten.de und seit 2011 Chef-Redakteur im Betten.de-Schlafmagazin.","url":"https:\/\/www.betten.de\/magazin\/author\/admin"}]}},"lang":"de-de","translations":{"de-de":38811,"de-at":38755},"pll_sync_post":{},"_links":{"self":[{"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/posts\/38811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/comments?post=38811"}],"version-history":[{"count":4,"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/posts\/38811\/revisions"}],"predecessor-version":[{"id":50203,"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/posts\/38811\/revisions\/50203"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/media\/38768"}],"wp:attachment":[{"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/media?parent=38811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/categories?post=38811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.betten.de\/magazin\/wp-json\/wp\/v2\/tags?post=38811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}